{"id":153,"date":"2014-04-26T19:10:42","date_gmt":"2014-04-26T19:10:42","guid":{"rendered":"http:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45.jpg"},"modified":"2014-04-26T19:10:42","modified_gmt":"2014-04-26T19:10:42","slug":"oops-we-did-it-again-45","status":"inherit","type":"attachment","link":"https:\/\/www.renegadeguild.net\/guild\/nakamuro-zatakis-nekkid-aerlinthe-run\/oops-we-did-it-again-45\/","title":{"rendered":"oops-we-did-it-again-45"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45.jpg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45-300x225.jpg 300w, https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45-150x112.jpg 150w, https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":450,"file":"oops-we-did-it-again-45.jpg","sizes":{"thumbnail":{"file":"oops-we-did-it-again-45-150x112.jpg","width":150,"height":112,"mime_type":"image\/jpeg","source_url":"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45-150x112.jpg"},"medium":{"file":"oops-we-did-it-again-45-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45-300x225.jpg"},"summary-image":{"file":"oops-we-did-it-again-45-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45-300x225.jpg"},"full":{"file":"oops-we-did-it-again-45.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":95,"source_url":"https:\/\/www.renegadeguild.net\/guild\/wp-content\/uploads\/oops-we-did-it-again-45.jpg","_links":{"self":[{"href":"https:\/\/www.renegadeguild.net\/guild\/wp-json\/wp\/v2\/media\/153"}],"collection":[{"href":"https:\/\/www.renegadeguild.net\/guild\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.renegadeguild.net\/guild\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.renegadeguild.net\/guild\/wp-json\/wp\/v2\/users\/1"}]}}